{"id":4008,"date":"2022-09-06T09:45:23","date_gmt":"2022-09-06T01:45:23","guid":{"rendered":"https:\/\/key2optics.com\/?page_id=4008"},"modified":"2022-11-04T16:55:59","modified_gmt":"2022-11-04T08:55:59","slug":"support-center","status":"publish","type":"page","link":"https:\/\/key2optics.com\/es\/centro-de-apoyo\/","title":{"rendered":"Apoyo"},"content":{"rendered":"<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-style-rounded\"><a href=\"https:\/\/key2optics.com\/es\/descargar\/\"><img loading=\"lazy\" decoding=\"async\" width=\"256\" height=\"256\" src=\"https:\/\/key2optics.com\/wp-content\/uploads\/2022\/09\/4299-Download-from-Cloud.png\" alt=\"\" class=\"wp-image-4038\" srcset=\"https:\/\/key2optics.com\/wp-content\/uploads\/2022\/09\/4299-Download-from-Cloud.png 256w, https:\/\/key2optics.com\/wp-content\/uploads\/2022\/09\/4299-Download-from-Cloud-100x100.png 100w, https:\/\/key2optics.com\/wp-content\/uploads\/2022\/09\/4299-Download-from-Cloud-180x180.png 180w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/><\/a><figcaption class=\"wp-element-caption\"><strong>Centro de descargas<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-style-rounded\"><a href=\"https:\/\/key2optics.com\/es\/pagina-de-preguntas-frecuentes\/\"><img loading=\"lazy\" decoding=\"async\" width=\"256\" height=\"256\" src=\"https:\/\/key2optics.com\/wp-content\/uploads\/2022\/09\/4309-Conversation-Bubbles.png\" alt=\"\" class=\"wp-image-4048\" srcset=\"https:\/\/key2optics.com\/wp-content\/uploads\/2022\/09\/4309-Conversation-Bubbles.png 256w, https:\/\/key2optics.com\/wp-content\/uploads\/2022\/09\/4309-Conversation-Bubbles-100x100.png 100w, https:\/\/key2optics.com\/wp-content\/uploads\/2022\/09\/4309-Conversation-Bubbles-180x180.png 180w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/><\/a><figcaption class=\"wp-element-caption\"><strong>Preguntas frecuentes sobre productos<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-style-rounded\"><a href=\"https:\/\/key2optics.com\/es\/oem-odm-servicios\/\"><img loading=\"lazy\" decoding=\"async\" width=\"256\" height=\"256\" src=\"https:\/\/key2optics.com\/wp-content\/uploads\/2022\/09\/4324-Chatting.png\" alt=\"\" class=\"wp-image-4063\" srcset=\"https:\/\/key2optics.com\/wp-content\/uploads\/2022\/09\/4324-Chatting.png 256w, https:\/\/key2optics.com\/wp-content\/uploads\/2022\/09\/4324-Chatting-100x100.png 100w, https:\/\/key2optics.com\/wp-content\/uploads\/2022\/09\/4324-Chatting-180x180.png 180w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/><\/a><figcaption class=\"wp-element-caption\"><strong>Servicios OED\/ODM<\/strong><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>P\u00f3ngase en contacto con nuestro correo electr\u00f3nico de soporte directamente: <a href=\"mailto:support@key2optics.com\" target=\"_blank\" rel=\"noopener\" title=\"\">support@key2optics.com<\/a> | +86 755 3289 4303 | <a href=\"https:\/\/wa.me\/message\/6F3QLD5JOVNLN1\" target=\"_blank\" rel=\"noopener\" title=\"\">WhatsApp<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Contacta directamente con nuestro servicio de asistencia por correo electr\u00f3nico: support@key2optics.com | +86 755 3289 [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/key2optics.com\/es\/wp-json\/wp\/v2\/pages\/4008"}],"collection":[{"href":"https:\/\/key2optics.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/key2optics.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/key2optics.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/key2optics.com\/es\/wp-json\/wp\/v2\/comments?post=4008"}],"version-history":[{"count":0,"href":"https:\/\/key2optics.com\/es\/wp-json\/wp\/v2\/pages\/4008\/revisions"}],"wp:attachment":[{"href":"https:\/\/key2optics.com\/es\/wp-json\/wp\/v2\/media?parent=4008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}